{"id":3059,"date":"2014-11-27T12:31:43","date_gmt":"2014-11-27T12:31:43","guid":{"rendered":"http:\/\/www.portatour.com\/blog\/?p=3059"},"modified":"2019-03-19T13:50:43","modified_gmt":"2019-03-19T13:50:43","slug":"trabajar-tambien-offline-con-el-planificador-de-rutas-portatour","status":"publish","type":"post","link":"https:\/\/www.portatour.com\/blog\/es\/trabajar-tambien-offline-con-el-planificador-de-rutas-portatour\/","title":{"rendered":"Trabajar tambi\u00e9n offline con portatour\u00ae"},"content":{"rendered":"<p>Quienes viajan mucho por motivos profesionales desafortunadamente conocen el problema: <strong>no en todas partes hay una conexi\u00f3n a Internet<\/strong>. Por eso, trabajamos para que siempre y en todas partes tenga acceso a su planificador de rutas portatour\u00ae y, por lo tanto, para ofrecerle un <strong>modo offline<\/strong> funcional.<\/p>\n<p><!--more--><\/p>\n<h2>Complete su ruta tambi\u00e9n offline<\/h2>\n<p>Todos los datos necesarios para su trabajo diario en el servicio de campo se almacenan temporalmente en su dispositivo:<\/p>\n<ul>\n<li>Su <strong>plan de visitas<\/strong> actual con las direcciones de destino<\/li>\n<li>Sus <strong>citas<\/strong> programadas<\/li>\n<li>Toda la informaci\u00f3n detallada sobre los <strong>clientes<\/strong> en su ruta<\/li>\n<li>Por ejemplo, la persona de contacto, el n\u00famero de tel\u00e9fono o el <strong>informe de la \u00faltima visita<\/strong><\/li>\n<\/ul>\n<p><span style=\"line-height: 1.714285714; font-size: 1rem;\">Acceda a esta informaci\u00f3n en cualquier momento, ya sea con conexi\u00f3n a Internet o sin ella. Su <\/span><span style=\"line-height: 1.714285714; font-size: 1rem;\"><a href=\"https:\/\/www.portatour.com\/es\">planificador de rutas portatour\u00ae<\/a> le mostrar\u00e1 de forma offline c\u00f3mo continuar su ruta:<\/span><\/p>\n<p><a href=\"http:\/\/www.portatour.com\/blog\/wp-content\/uploads\/Offline-Besuchsplan-ES.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-402\" src=\"http:\/\/www.portatour.com\/blog\/wp-content\/uploads\/Offline-Besuchsplan-ES.png\" alt=\"Plan de visitas\/de rutas accesible offline\" width=\"320\" height=\"418\" \/><\/a><\/p>\n<h2>Redacte informes de visita tambi\u00e9n offline<\/h2>\n<p>Si desea incluir informaci\u00f3n importante en un informe de visita inmediatamente despu\u00e9s de la visita al cliente, no tener Internet no le impedir\u00e1 trabajar. Simplemente redacte el informe offline en portatour\u00ae. As\u00ed no tendr\u00e1 que esperar hasta la noche y tendr\u00e1 la cabeza libre para la visita al pr\u00f3ximo cliente. Cuando vuelva a estar en l\u00ednea con conexi\u00f3n a portatour\u00ae, sus informes se cargar\u00e1n autom\u00e1ticamente.<\/p>\n<h2>Es muy simple: ni aplicaciones, ni instalaci\u00f3n<\/h2>\n<p>La funcionalidad offline est\u00e1 disponible en portatour\u00ae Anywhere directamente en su navegador web, ya sea en un port\u00e1til, tableta o smartphone. Tampoco es necesario instalar una aplicaci\u00f3n o un software de sincronizaci\u00f3n complicado. Los datos necesarios para el modo offline se descargan autom\u00e1ticamente en segundo plano mientras trabaja con portatour\u00ae online. No tiene que preocuparse por nada. Si se interrumpe la conexi\u00f3n a Internet, simplemente siga trabajando en modo offline (*).<\/p>\n<p>As\u00ed, usando el planificador de rutas portatour\u00ae, \u00a1nada le impedir\u00e1 trabajar con aquellos clientes a los que ni siquiera llega Internet! \ud83d\ude42<\/p>\n<p><em>(*) Nota para usuarios: la funcionalidad offline no est\u00e1 habilitada por defecto. Para hacerlo, vaya a Opciones -&gt; Ajustes del programa -&gt; Actualizar datos sin conexi\u00f3n, y adapte el ajuste una vez.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quienes viajan mucho por motivos profesionales desafortunadamente conocen el problema: no en todas partes hay una conexi\u00f3n a Internet. Por eso, trabajamos para que siempre y en todas partes tenga acceso a su planificador de rutas portatour\u00ae y, por lo tanto, para ofrecerle un modo offline funcional.<\/p>\n","protected":false},"author":16,"featured_media":2328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-planificacion-de-rutas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/posts\/3059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=3059"}],"version-history":[{"count":6,"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/posts\/3059\/revisions"}],"predecessor-version":[{"id":3427,"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/posts\/3059\/revisions\/3427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/media\/2328"}],"wp:attachment":[{"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=3059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=3059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portatour.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=3059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}